{"id":11099,"date":"2025-01-16T11:23:06","date_gmt":"2025-01-16T10:23:06","guid":{"rendered":"https:\/\/www.respirelavie.fr\/rennes\/?p=11099"},"modified":"2025-01-16T11:23:06","modified_gmt":"2025-01-16T10:23:06","slug":"helene-girardin","status":"publish","type":"post","link":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/","title":{"rendered":"H\u00e9l\u00e8ne Girardin"},"content":{"rendered":"<h2>Si vous pouviez avoir un super-pouvoir, lequel choisiriez-vous et pourquoi ?<\/h2>\n<div>\n<div><\/div>\n<\/div>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-15893 size-full\" src=\"https:\/\/www.salon-zenetbio.com\/nantes\/wp-content\/uploads\/sites\/7\/2024\/09\/AMOUR-DE-SOI.jpg\" alt=\"H\u00e9l\u00e8ne Girardin - illustration\" width=\"274\" height=\"184\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Le pouvoir de gu\u00e9rir les blessures du pass\u00e9 pour vivre l&#8217;instant pr\u00e9sent, car notre personnalit\u00e9 est bas\u00e9e sur notre enfance.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>Si vous pouviez d\u00eener avec une personne c\u00e9l\u00e8bre, vivante ou d\u00e9c\u00e9d\u00e9e, qui serait-ce et pourquoi ?<\/h2>\n<div>\n<div>Milton Erickson pour moi c&#8217;est un g\u00e9nie et un pr\u00e9curseur de l&#8217;hypnoth\u00e9rapie.<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div><\/div>\n<div>\n<h2>Si vous deviez choisir une chanson pour repr\u00e9senter votre activit\u00e9, laquelle serait-elle ?<\/h2>\n<div><\/div>\n<div>&#8220;Prendre un enfant par la main&#8221; d&#8217;Yves Duteil.<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<h2>Qui est H\u00e9l\u00e8ne Girardin ?<\/h2>\n<div><\/div>\n<div>\n<div>Je suis th\u00e9rapeute sp\u00e9cialis\u00e9e dans la r\u00e9silience et la gu\u00e9rison des blessures du pass\u00e9. <a href=\"https:\/\/www.facebook.com\/profile.php?id=100062963993927&amp;locale=fr_FR\" target=\"_blank\" rel=\"noopener\">J&#8217;accompagne<\/a> mes participants dans un processus de transformation personnelle en utilisant des techniques adapt\u00e9es, les aidant \u00e0 retrouver leur force int\u00e9rieure et \u00e0 embrasser leur histoire pour vivre une vie plus \u00e9panouissante.<\/div>\n<\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-15894 size-full\" src=\"https:\/\/www.salon-zenetbio.com\/nantes\/wp-content\/uploads\/sites\/7\/2024\/09\/lpp-ei.jpg\" alt=\"H\u00e9l\u00e8ne Girardin - illustration 2\" width=\"255\" height=\"197\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Quel est votre \u00ab incontournable \u00bb \u00e0 trouver sur votre stand ?<\/h2>\n<div><\/div>\n<div>\n<div>Atelier de gu\u00e9rison et livre &#8220;notre enfant int\u00e9rieur est-il notre meilleur th\u00e9rapeute.<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<h2><a href=\"https:\/\/www.respirelavie.fr\/rennes\/visiter\/liste-des-exposants\/\" target=\"_blank\" rel=\"noopener\"><em style=\"font-size: 17px; font-weight: 400;\">Consultez la liste des exposants 2025<\/em><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Si vous pouviez avoir un super-pouvoir, lequel choisiriez-vous et pourquoi ? &nbsp; Le pouvoir de gu\u00e9rir les blessures du pass\u00e9 pour vivre l&#8217;instant pr\u00e9sent, car notre personnalit\u00e9 est bas\u00e9e sur notre enfance. &nbsp; &nbsp; &nbsp; Si vous pouviez d\u00eener avec une personne c\u00e9l\u00e8bre, vivante ou d\u00e9c\u00e9d\u00e9e, qui serait-ce et pourquoi ? Milton Erickson pour moi&hellip; <\/p>\n","protected":false},"author":5,"featured_media":11101,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[358],"tags":[],"class_list":["post-11099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portraits-exposants"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H\u00e9l\u00e8ne Girardin - Respire La Vie Rennes<\/title>\n<meta name=\"description\" content=\"H\u00e9l\u00e8ne Girardin sera ravie de vous rencontrer lors du salon Respire La Vie sur Rennes du 21 au 23 f\u00e9vrier 2025 !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00e9l\u00e8ne Girardin - Respire La Vie Rennes\" \/>\n<meta property=\"og:description\" content=\"H\u00e9l\u00e8ne Girardin sera ravie de vous rencontrer lors du salon Respire La Vie sur Rennes du 21 au 23 f\u00e9vrier 2025 !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/\" \/>\n<meta property=\"og:site_name\" content=\"Respire La Vie Rennes\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-16T10:23:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.respirelavie.fr\/rennes\/wp-content\/uploads\/sites\/5\/2024\/12\/AMOUR-DE-SOI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"274\" \/>\n\t<meta property=\"og:image:height\" content=\"184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"communication\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"communication\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/\"},\"author\":{\"name\":\"communication\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#\\\/schema\\\/person\\\/773bfe7c31181098698bacd32c5d233c\"},\"headline\":\"H\u00e9l\u00e8ne Girardin\",\"datePublished\":\"2025-01-16T10:23:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/\"},\"wordCount\":193,\"publisher\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/12\\\/AMOUR-DE-SOI.jpg\",\"articleSection\":[\"Portraits d'exposants\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/\",\"url\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/\",\"name\":\"H\u00e9l\u00e8ne Girardin - Respire La Vie Rennes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/12\\\/AMOUR-DE-SOI.jpg\",\"datePublished\":\"2025-01-16T10:23:06+00:00\",\"description\":\"H\u00e9l\u00e8ne Girardin sera ravie de vous rencontrer lors du salon Respire La Vie sur Rennes du 21 au 23 f\u00e9vrier 2025 !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/12\\\/AMOUR-DE-SOI.jpg\",\"contentUrl\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/12\\\/AMOUR-DE-SOI.jpg\",\"width\":274,\"height\":184},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/2025\\\/01\\\/16\\\/helene-girardin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00e9l\u00e8ne Girardin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#website\",\"url\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/\",\"name\":\"Respire La Vie Rennes\",\"description\":\"Respire La Vie Rennes : votre salon \u00e9colo, bio, bien-\u00eatre et habitat sain \u00e0 Rennes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#organization\",\"name\":\"Respire La Vie Rennes\",\"url\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/11\\\/cropped-Logo-RESPIRE-rennes-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/11\\\/cropped-Logo-RESPIRE-rennes-2026.png\",\"width\":921,\"height\":255,\"caption\":\"Respire La Vie Rennes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/#\\\/schema\\\/person\\\/773bfe7c31181098698bacd32c5d233c\",\"name\":\"communication\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f49d5b7ab56355ffa797b3ce25e4f2375cedf6bc9afe416fe669342c3524275?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f49d5b7ab56355ffa797b3ce25e4f2375cedf6bc9afe416fe669342c3524275?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f49d5b7ab56355ffa797b3ce25e4f2375cedf6bc9afe416fe669342c3524275?s=96&d=mm&r=g\",\"caption\":\"communication\"},\"url\":\"https:\\\/\\\/www.respirelavie.fr\\\/rennes\\\/blog\\\/author\\\/communication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00e9l\u00e8ne Girardin - Respire La Vie Rennes","description":"H\u00e9l\u00e8ne Girardin sera ravie de vous rencontrer lors du salon Respire La Vie sur Rennes du 21 au 23 f\u00e9vrier 2025 !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/","og_locale":"fr_FR","og_type":"article","og_title":"H\u00e9l\u00e8ne Girardin - Respire La Vie Rennes","og_description":"H\u00e9l\u00e8ne Girardin sera ravie de vous rencontrer lors du salon Respire La Vie sur Rennes du 21 au 23 f\u00e9vrier 2025 !","og_url":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/","og_site_name":"Respire La Vie Rennes","article_published_time":"2025-01-16T10:23:06+00:00","og_image":[{"width":274,"height":184,"url":"https:\/\/www.respirelavie.fr\/rennes\/wp-content\/uploads\/sites\/5\/2024\/12\/AMOUR-DE-SOI.jpg","type":"image\/jpeg"}],"author":"communication","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"communication","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/#article","isPartOf":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/"},"author":{"name":"communication","@id":"https:\/\/www.respirelavie.fr\/rennes\/#\/schema\/person\/773bfe7c31181098698bacd32c5d233c"},"headline":"H\u00e9l\u00e8ne Girardin","datePublished":"2025-01-16T10:23:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/"},"wordCount":193,"publisher":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/#organization"},"image":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.respirelavie.fr\/rennes\/wp-content\/uploads\/sites\/5\/2024\/12\/AMOUR-DE-SOI.jpg","articleSection":["Portraits d'exposants"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/","url":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/","name":"H\u00e9l\u00e8ne Girardin - Respire La Vie Rennes","isPartOf":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/#primaryimage"},"image":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.respirelavie.fr\/rennes\/wp-content\/uploads\/sites\/5\/2024\/12\/AMOUR-DE-SOI.jpg","datePublished":"2025-01-16T10:23:06+00:00","description":"H\u00e9l\u00e8ne Girardin sera ravie de vous rencontrer lors du salon Respire La Vie sur Rennes du 21 au 23 f\u00e9vrier 2025 !","breadcrumb":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/#primaryimage","url":"https:\/\/www.respirelavie.fr\/rennes\/wp-content\/uploads\/sites\/5\/2024\/12\/AMOUR-DE-SOI.jpg","contentUrl":"https:\/\/www.respirelavie.fr\/rennes\/wp-content\/uploads\/sites\/5\/2024\/12\/AMOUR-DE-SOI.jpg","width":274,"height":184},{"@type":"BreadcrumbList","@id":"https:\/\/www.respirelavie.fr\/rennes\/blog\/2025\/01\/16\/helene-girardin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.respirelavie.fr\/rennes\/"},{"@type":"ListItem","position":2,"name":"H\u00e9l\u00e8ne Girardin"}]},{"@type":"WebSite","@id":"https:\/\/www.respirelavie.fr\/rennes\/#website","url":"https:\/\/www.respirelavie.fr\/rennes\/","name":"Respire La Vie Rennes","description":"Respire La Vie Rennes : votre salon \u00e9colo, bio, bien-\u00eatre et habitat sain \u00e0 Rennes","publisher":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.respirelavie.fr\/rennes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.respirelavie.fr\/rennes\/#organization","name":"Respire La Vie Rennes","url":"https:\/\/www.respirelavie.fr\/rennes\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.respirelavie.fr\/rennes\/#\/schema\/logo\/image\/","url":"https:\/\/www.respirelavie.fr\/rennes\/wp-content\/uploads\/sites\/5\/2025\/11\/cropped-Logo-RESPIRE-rennes-2026.png","contentUrl":"https:\/\/www.respirelavie.fr\/rennes\/wp-content\/uploads\/sites\/5\/2025\/11\/cropped-Logo-RESPIRE-rennes-2026.png","width":921,"height":255,"caption":"Respire La Vie Rennes"},"image":{"@id":"https:\/\/www.respirelavie.fr\/rennes\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.respirelavie.fr\/rennes\/#\/schema\/person\/773bfe7c31181098698bacd32c5d233c","name":"communication","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0f49d5b7ab56355ffa797b3ce25e4f2375cedf6bc9afe416fe669342c3524275?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f49d5b7ab56355ffa797b3ce25e4f2375cedf6bc9afe416fe669342c3524275?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f49d5b7ab56355ffa797b3ce25e4f2375cedf6bc9afe416fe669342c3524275?s=96&d=mm&r=g","caption":"communication"},"url":"https:\/\/www.respirelavie.fr\/rennes\/blog\/author\/communication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/posts\/11099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/comments?post=11099"}],"version-history":[{"count":4,"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/posts\/11099\/revisions"}],"predecessor-version":[{"id":11344,"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/posts\/11099\/revisions\/11344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/media\/11101"}],"wp:attachment":[{"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/media?parent=11099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/categories?post=11099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.respirelavie.fr\/rennes\/wp-json\/wp\/v2\/tags?post=11099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}